{"id":4821,"date":"2015-07-15T12:14:15","date_gmt":"2015-07-15T03:14:15","guid":{"rendered":"http:\/\/www.waseda.jp\/fpse\/pse\/?p=4821"},"modified":"2015-07-15T12:14:15","modified_gmt":"2015-07-15T03:14:15","slug":"%e9%96%8b%e5%ae%a4%e6%99%82%e9%96%93%e7%9f%ad%e7%b8%ae%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b%ef%bc%9a%e6%9d%8e%e5%81%a5%e7%86%99%e8%a8%98%e5%bf%b5%e5%9b%b3%e6%9b%b8%e5%ae%a4%e6%94%bf%e6%b2%bb","status":"publish","type":"post","link":"https:\/\/www.waseda.jp\/fpse\/pse\/news\/2015\/07\/15\/4821\/","title":{"rendered":"\u958b\u5ba4\u6642\u9593\u77ed\u7e2e\u306e\u304a\u77e5\u3089\u305b\uff1a\u674e\u5065\u7199\u8a18\u5ff5\u56f3\u66f8\u5ba4(\u653f\u6cbb\u7d4c\u6e08\u5b66\u8853\u9662\u5b66\u751f\u8aad\u66f8\u5ba4\uff09"},"content":{"rendered":"<p style=\"text-align: center;\">\u30aa\u30fc\u30d7\u30f3\u30ad\u30e3\u30f3\u30d1\u30b9\uff12\uff10\uff11\uff15\u306e\u6e96\u5099\u306e\u305f\u3081\u3001<br \/>\n\u653f\u6cbb\u7d4c\u6e08\u5b66\u8853\u9662\u5b66\u751f\u8aad\u66f8\u5ba4\u306f\u3001\u4ee5\u4e0b\u306e\u901a\u308a\u958b\u5ba4\u6642\u9593\u3092\u77ed\u7e2e\u3057\u307e\u3059\u3002<\/p>\n<p style=\"text-align: center;\">\uff12\uff10\uff11\uff15\u5e74\uff17\u6708\uff13\uff11\u65e5(\u91d1)\u3000\uff19\uff1a\uff10\uff10\uff5e\uff11\uff18\uff1a\uff10\uff10<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u30aa\u30fc\u30d7\u30f3\u30ad\u30e3\u30f3\u30d1\u30b9\uff12\uff10\uff11\uff15\u306e\u6e96\u5099\u306e\u305f\u3081\u3001 \u653f\u6cbb\u7d4c\u6e08\u5b66\u8853\u9662\u5b66\u751f\u8aad\u66f8\u5ba4\u306f\u3001\u4ee5\u4e0b\u306e\u901a\u308a\u958b\u5ba4\u6642\u9593\u3092\u77ed\u7e2e\u3057\u307e\u3059\u3002 \uff12\uff10\uff11\uff15\u5e74\uff17\u6708\uff13\uff11\u65e5(\u91d1)\u3000\uff19\uff1a\uff10\uff10\uff5e\uff11\uff18\uff1a\uff10\uff10<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[13],"class_list":["post-4821","post","type-post","status-publish","format-standard","hentry","category-news","tag-student"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/posts\/4821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/comments?post=4821"}],"version-history":[{"count":1,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/posts\/4821\/revisions"}],"predecessor-version":[{"id":4823,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/posts\/4821\/revisions\/4823"}],"wp:attachment":[{"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/media?parent=4821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/categories?post=4821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/tags?post=4821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}