{"id":17658,"date":"2022-12-06T15:08:16","date_gmt":"2022-12-06T06:08:16","guid":{"rendered":"https:\/\/www.waseda.jp\/fpse\/pse\/?p=17658"},"modified":"2022-12-06T15:08:16","modified_gmt":"2022-12-06T06:08:16","slug":"%e9%96%8b%e5%ae%a4%e6%99%82%e9%96%93%e5%bb%b6%e9%95%b7%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b%ef%bc%9a%e6%9d%8e%e5%81%a5%e7%86%99%e8%a8%98%e5%bf%b5%e5%9b%b3%e6%9b%b8%e5%ae%a4%e6%94%bf-10-3-3","status":"publish","type":"post","link":"https:\/\/www.waseda.jp\/fpse\/pse\/news\/2022\/12\/06\/17658\/","title":{"rendered":"\u958b\u5ba4\u6642\u9593\u5ef6\u9577\u306e\u304a\u77e5\u3089\u305b\uff1a\u674e\u5065\u7199\u8a18\u5ff5\u56f3\u66f8\u5ba4(\u653f\u6cbb\u7d4c\u6e08\u5b66\u8853\u9662\u5b66\u751f\u8aad\u66f8\u5ba4\uff09"},"content":{"rendered":"<p>\u653f\u6cbb\u7d4c\u6e08\u5b66\u8853\u9662\u5b66\u751f\u8aad\u66f8\u5ba4\u306f\u4ee5\u4e0b\u306e\u901a\u308a\u958b\u5ba4\u6642\u9593\u3092\u5ef6\u9577\u3057\u307e\u3059\u3002<\/p>\n<p style=\"background: white;\">2023\u5e741\u6708 7\u65e5(\u571f)\u30009\uff1a00\uff5e22\uff1a00<br \/>\n2023\u5e741\u6708 14\u65e5(\u571f)\u30009\uff1a00\uff5e22\uff1a00<br \/>\n2023\u5e741\u6708 21\u65e5(\u571f)\u30009\uff1a00\uff5e22\uff1a00<\/p>\n<p>*\u571f\u66dc\u65e5\uff08\u901a\u5e38\u671f\uff09\u306e\u958b\u5ba4\u6642\u9593\uff1a\u30009\uff1a00\uff5e18\uff1a00<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u653f\u6cbb\u7d4c\u6e08\u5b66\u8853\u9662\u5b66\u751f\u8aad\u66f8\u5ba4\u306f\u4ee5\u4e0b\u306e\u901a\u308a\u958b\u5ba4\u6642\u9593\u3092\u5ef6\u9577\u3057\u307e\u3059\u3002 2023\u5e741\u6708 7\u65e5(\u571f)\u30009\uff1a00\uff5e22\uff1a00 2023\u5e741\u6708 14\u65e5(\u571f)\u30009\uff1a00\uff5e22\uff1a00 2023\u5e741\u6708 21\u65e5(\u571f)\u30009\uff1a00\uff5e22\uff1a00 *\u571f\u66dc [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[13,60,138],"class_list":["post-17658","post","type-post","status-publish","format-standard","hentry","category-news","tag-student","tag-alumni","tag-general"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/posts\/17658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/comments?post=17658"}],"version-history":[{"count":1,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/posts\/17658\/revisions"}],"predecessor-version":[{"id":17659,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/posts\/17658\/revisions\/17659"}],"wp:attachment":[{"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/media?parent=17658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/categories?post=17658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/tags?post=17658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}