{"id":15203,"date":"2022-03-17T13:43:01","date_gmt":"2022-03-17T04:43:01","guid":{"rendered":"https:\/\/www.waseda.jp\/fpse\/pse\/?p=15203"},"modified":"2022-06-24T10:01:05","modified_gmt":"2022-06-24T01:01:05","slug":"%e6%97%a9%e7%a8%b2%e7%94%b0%e5%a4%a7%e5%ad%a6%e6%94%bf%e6%b2%bb%e7%b5%8c%e6%b8%88%e5%ad%a6%e9%83%a8-%e6%96%b0%e5%85%a5%e7%94%9f%e6%ad%93%e8%bf%8e%e3%82%b7%e3%83%b3%e3%83%9d%e3%82%b8%e3%82%a6-3","status":"publish","type":"post","link":"https:\/\/www.waseda.jp\/fpse\/pse\/news\/2022\/03\/17\/15203\/","title":{"rendered":"\u65e9\u7a32\u7530\u5927\u5b66\u653f\u6cbb\u7d4c\u6e08\u5b66\u90e8 \u5165\u5b66\u5f0f\u306b\u3064\u3044\u3066"},"content":{"rendered":"<p>\u65b0\u5165\u751f\u306e\u307f\u306a\u3055\u307e<\/p>\n<p>2022\u5e74\u5ea6\u306e\u653f\u6cbb\u7d4c\u6e08\u5b66\u90e8\u5165\u5b66\u5f0f\u306f\u4ee5\u4e0b\u306e\u3068\u304a\u308a\u958b\u50ac\u3044\u305f\u3057\u307e\u3059\u3002<\/p>\n<p>\u65e5\u3000\u6642\uff1a4\u67081\u65e5\uff08\u91d1\uff0912:00 &#8211; 12:45\uff08\u958b\u5834\u4e88\u5b9a\uff1a11:30\uff09<br \/>\n\u5834\u3000\u6240\uff1a\u65e9\u7a32\u7530\u30ad\u30e3\u30f3\u30d1\u30b9\u3000\u5927\u9688\u8a18\u5ff5\u8b1b\u5802<\/p>\n<p>\u5927\u5b66\u5168\u4f53\u306e\u5165\u5b66\u5f0f\u304c\u6238\u5c71\u30ad\u30e3\u30f3\u30d1\u30b9\u306e\u65e9\u7a32\u7530\u30a2\u30ea\u30fc\u30ca\u306710:45\u9803\u307e\u3067\u958b\u50ac\u3055\u308c\u308b\u4e88\u5b9a\u3067\u3059\u3002<br \/>\n\u5168\u4f53\u306e\u5165\u5b66\u5f0f\u304c\u7d42\u4e86\u3057\u307e\u3057\u305f\u3089\u3001\u76f4\u63a5\u5927\u9688\u8a18\u5ff5\u8b1b\u5802\u524d\u306e\u5e83\u5834\u306b\u304a\u96c6\u307e\u308a\u304f\u3060\u3055\u3044\u3002<\/p>\n<p>\u7559\u610f\u70b9<br \/>\n\u30fb\u4f53\u8abf\u304c\u3059\u3050\u308c\u306a\u3044\u5834\u5408\u306f\u51fa\u5e2d\u3092\u304a\u63a7\u3048\u304f\u3060\u3055\u3044\u3002<br \/>\n\u30fb\u65b0\u5165\u751f\u306e\u307f\u3054\u5165\u5834\u3067\u304d\u307e\u3059\u3002<br \/>\n\u30fb\u5165\u5834\u306e\u969b\u306f\u4e0d\u7e54\u5e03\u30de\u30b9\u30af\u3092\u7740\u7528\u3057\u3066\u304f\u3060\u3055\u3044\u3002<br \/>\n\u30fb\u5165\u5b66\u5f0f\u7d42\u4e86\u5f8c\u306f3\u53f7\u9928\u306b\u3066\u5b66\u751f\u8a3c\u306e\u4ea4\u4ed8\u304c\u3042\u308a\u307e\u3059\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u65b0\u5165\u751f\u306e\u307f\u306a\u3055\u307e 2022\u5e74\u5ea6\u306e\u653f\u6cbb\u7d4c\u6e08\u5b66\u90e8\u5165\u5b66\u5f0f\u306f\u4ee5\u4e0b\u306e\u3068\u304a\u308a\u958b\u50ac\u3044\u305f\u3057\u307e\u3059\u3002 \u65e5\u3000\u6642\uff1a4\u67081\u65e5\uff08\u91d1\uff0912:00 &#8211; 12:45\uff08\u958b\u5834\u4e88\u5b9a\uff1a11:30\uff09 \u5834\u3000\u6240\uff1a\u65e9\u7a32\u7530\u30ad\u30e3\u30f3\u30d1\u30b9\u3000\u5927\u9688\u8a18\u5ff5\u8b1b\u5802 \u5927\u5b66\u5168\u4f53\u306e\u5165 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11821,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[13,133,138],"class_list":["post-15203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-student","tag-events","tag-general"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/posts\/15203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/comments?post=15203"}],"version-history":[{"count":1,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/posts\/15203\/revisions"}],"predecessor-version":[{"id":16325,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/posts\/15203\/revisions\/16325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/media\/11821"}],"wp:attachment":[{"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/media?parent=15203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/categories?post=15203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/tags?post=15203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}