{"id":12621,"date":"2020-12-23T11:20:44","date_gmt":"2020-12-23T02:20:44","guid":{"rendered":"https:\/\/www.waseda.jp\/fpse\/pse\/?p=12621"},"modified":"2020-12-23T11:20:44","modified_gmt":"2020-12-23T02:20:44","slug":"%e4%ba%8b%e5%8b%99%e6%89%80%e9%96%89%e5%ae%a4%e6%9c%9f%e9%96%93%e4%b8%ad%e3%81%ae%e6%a5%ad%e5%8b%99%e3%81%ae%e5%8f%96%e6%89%b1%e3%81%84%e3%81%ab%e3%81%a4%e3%81%84%e3%81%a6%e6%94%bf%e6%b2%bb%e7%b5%8c-5","status":"publish","type":"post","link":"https:\/\/www.waseda.jp\/fpse\/pse\/news\/2020\/12\/23\/12621\/","title":{"rendered":"\u5b66\u751f\u8aad\u66f8\u5ba4\u306e\u958b\u5ba4\u6642\u9593\u5ef6\u9577\u306e\u304a\u77e5\u3089\u305b\uff082020\u5e741\u6708\uff09"},"content":{"rendered":"<p>\u674e\u5065\u7199\u8a18\u5ff5\u56f3\u66f8\u5ba4(\u653f\u6cbb\u7d4c\u6e08\u5b66\u8853\u9662\u5b66\u751f\u8aad\u66f8\u5ba4\uff09\u306f\u4ee5\u4e0b\u306e\u901a\u308a\u958b\u5ba4\u6642\u9593\u3092\u5ef6\u9577\u3057\u307e\u3059\u3002<\/p>\n<p>2021\u5e741\u6708  9\u65e5(\u571f)\u30009\uff1a00\uff5e22\uff1a00<br \/>\n2021\u5e741\u6708 16\u65e5(\u571f)\u30009\uff1a00\uff5e22\uff1a00<br \/>\n2021\u5e741\u6708 23\u65e5(\u571f)\u30009\uff1a00\uff5e22\uff1a00<br \/>\n2021\u5e741\u6708 30\u65e5(\u571f)  9\uff1a00\uff5e18\uff1a00<\/p>\n<p>*\u571f\u66dc\u65e5\uff08\u901a\u5e38\u671f\uff09\u306e\u958b\u5ba4\u6642\u9593\uff1a\u30009\uff1a00\uff5e18\uff1a00<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u674e\u5065\u7199\u8a18\u5ff5\u56f3\u66f8\u5ba4(\u653f\u6cbb\u7d4c\u6e08\u5b66\u8853\u9662\u5b66\u751f\u8aad\u66f8\u5ba4\uff09\u306f\u4ee5\u4e0b\u306e\u901a\u308a\u958b\u5ba4\u6642\u9593\u3092\u5ef6\u9577\u3057\u307e\u3059\u3002 2021\u5e741\u6708 9\u65e5(\u571f)\u30009\uff1a00\uff5e22\uff1a00 2021\u5e741\u6708 16\u65e5(\u571f)\u30009\uff1a00\uff5e22\uff1a00 2021\u5e741\u6708 23\u65e5(\u571f)\u30009\uff1a00 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[13,60,138],"class_list":["post-12621","post","type-post","status-publish","format-standard","hentry","category-news","tag-student","tag-alumni","tag-general"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/posts\/12621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/comments?post=12621"}],"version-history":[{"count":0,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/posts\/12621\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/media?parent=12621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/categories?post=12621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/tags?post=12621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}