{"id":11037,"date":"2019-10-11T16:14:27","date_gmt":"2019-10-11T07:14:27","guid":{"rendered":"https:\/\/www.waseda.jp\/fpse\/pse\/?p=11037"},"modified":"2019-10-11T16:21:40","modified_gmt":"2019-10-11T07:21:40","slug":"__trashed-3","status":"publish","type":"post","link":"https:\/\/www.waseda.jp\/fpse\/pse\/news\/2019\/10\/11\/11037\/","title":{"rendered":"10\u670812\u65e5\uff08\u571f\uff09\u306e\u4e8b\u52d9\u6240\u81e8\u6642\u9589\u5ba4\u306b\u3064\u3044\u3066"},"content":{"rendered":"<p>10\u670812\u65e5\uff08\u571f\uff09\u306f\u3001\u53f0\u98a819\u53f7\u306e\u63a5\u8fd1\u30fb\u901a\u904e\u306b\u4f34\u3046\u3001\u5168\u5b66\u4f11\u8b1b\u306b\u4f34\u3044\u3001\u5f53\u5b66\u90e8\u4e8b\u52d9\u6240\u3092\u81e8\u6642\u9589\u5ba4\u3044\u305f\u3057\u307e\u3059\u3002<br \/>\n\u6050\u308c\u5165\u308a\u307e\u3059\u304c\u3001\u3054\u7528\u306e\u3042\u308b\u65b9\u306f\u300110\u670814\u65e59:00\u4ee5\u964d\u306b\u304a\u554f\u3044\u5408\u308f\u305b\u304f\u3060\u3055\u3044\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>10\u670812\u65e5\uff08\u571f\uff09\u306f\u3001\u53f0\u98a819\u53f7\u306e\u63a5\u8fd1\u30fb\u901a\u904e\u306b\u4f34\u3046\u3001\u5168\u5b66\u4f11\u8b1b\u306b\u4f34\u3044\u3001\u5f53\u5b66\u90e8\u4e8b\u52d9\u6240\u3092\u81e8\u6642\u9589\u5ba4\u3044\u305f\u3057\u307e\u3059\u3002 \u6050\u308c\u5165\u308a\u307e\u3059\u304c\u3001\u3054\u7528\u306e\u3042\u308b\u65b9\u306f\u300110\u670814\u65e59:00\u4ee5\u964d\u306b\u304a\u554f\u3044\u5408\u308f\u305b\u304f\u3060\u3055\u3044\u3002<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[13,64,138],"class_list":["post-11037","post","type-post","status-publish","format-standard","hentry","category-news","tag-student","tag-global","tag-general"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/posts\/11037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/comments?post=11037"}],"version-history":[{"count":0,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/posts\/11037\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/media?parent=11037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/categories?post=11037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.waseda.jp\/fpse\/pse\/wp-json\/wp\/v2\/tags?post=11037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}